{"id":8981,"date":"2023-11-10T15:20:36","date_gmt":"2023-11-10T07:20:36","guid":{"rendered":"https:\/\/www.oc-lawyers.com.cn\/?p=8981"},"modified":"2023-11-10T15:20:41","modified_gmt":"2023-11-10T07:20:41","slug":"%e7%a5%a8%e6%8d%ae%e7%ba%a0%e7%ba%b7%e6%b3%95%e5%be%8b%e5%85%b3%e7%b3%bb%e7%ae%80%e8%bf%b0","status":"publish","type":"post","link":"https:\/\/www.oc-lawyers.com.cn\/en\/%e7%a5%a8%e6%8d%ae%e7%ba%a0%e7%ba%b7%e6%b3%95%e5%be%8b%e5%85%b3%e7%b3%bb%e7%ae%80%e8%bf%b0\/","title":{"rendered":"\u7968\u636e\u7ea0\u7eb7\u6cd5\u5f8b\u5173\u7cfb\u7b80\u8ff0"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"8981\" class=\"elementor elementor-8981\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-551c3dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"551c3dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4207691\" data-id=\"4207691\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a89b26 elementor-align-left elementor-widget elementor-widget-raven-breadcrumbs\" data-id=\"3a89b26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"raven-breadcrumbs raven-breadcrumbs-default\"><div class=\"breadcrumb\">\t\t\t\t\t\t\t\t<div class=\"breadcrumb-item active\" aria-current=\"page\"><span>Home<\/span><\/div>\n\n\t\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-163a909 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"163a909\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-900d06e\" data-id=\"900d06e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1be8234 elementor-widget elementor-widget-heading\" data-id=\"1be8234\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u7968\u636e\u7ea0\u7eb7\u6cd5\u5f8b\u5173\u7cfb\u7b80\u8ff0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b0e5d1 elementor-align-center elementor-widget elementor-widget-raven-post-meta\" data-id=\"5b0e5d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-post-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"raven-inline-items raven-icon-list-items raven-post-meta\">\n\t\t\t\t\t<li class=\"raven-icon-list-item elementor-repeater-item-f3da4a5 raven-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.oc-lawyers.com.cn\/en\/2023\/11\/10\/\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"raven-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-calendar\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"raven-icon-list-text raven-post-meta-item raven-post-meta-item-type-date\">\n\t\t\t\t\t\t\t\t\t\t2023-11-10\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"raven-icon-list-item elementor-repeater-item-a47c45a raven-inline-item\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t<span class=\"raven-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tags\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"raven-icon-list-text raven-post-meta-item raven-post-meta-item-type-terms raven-terms-list\">\n\t\t\t\t\t\t\t<span class=\"raven-post-meta-item-prefix\">\u5173\u952e\u8bcd\uff1a<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"raven-post-meta-terms-list\">\n\t\t\t\t<a href=\"https:\/\/www.oc-lawyers.com.cn\/en\/tag\/evidential-burden\/\" class=\"raven-post-meta-terms-list-item\">\u4e3e\u8bc1\u8d23\u4efb<\/a>, <a href=\"https:\/\/www.oc-lawyers.com.cn\/en\/tag\/arbitration\/\" class=\"raven-post-meta-terms-list-item\">\u4ef2\u88c1<\/a>, <a href=\"https:\/\/www.oc-lawyers.com.cn\/en\/tag\/contract-law\/\" class=\"raven-post-meta-terms-list-item\">\u5408\u540c\u6cd5<\/a>, <a href=\"https:\/\/www.oc-lawyers.com.cn\/en\/tag\/civil-procedure\/\" class=\"raven-post-meta-terms-list-item\">\u6c11\u4e8b\u8bc9\u8bbc<\/a>, <a href=\"https:\/\/www.oc-lawyers.com.cn\/en\/tag\/mediation\/\" class=\"raven-post-meta-terms-list-item\">\u8c03\u89e3<\/a>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"raven-icon-list-item elementor-repeater-item-f6d2614 raven-inline-item\">\n\t\t\t\t\t\t\t\t\t<span class=\"raven-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pencil-alt\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"raven-icon-list-text raven-post-meta-item raven-post-meta-item-type-custom\">\n\t\t\t\t\t\t\t\t\t\t\u4f5c\u8005\uff1a\u5f90\u6770\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65f98b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65f98b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c461c3e\" data-id=\"c461c3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d045af elementor-widget elementor-widget-text-editor\" data-id=\"1d045af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><b>\u6458\u8981<\/b><\/strong><\/p><p>\u00a0\u672c\u6587\u65e8\u5728\u5bf9\u7968\u636e\u7ea0\u7eb7\u6848\u4ef6\u8fdb\u884c\u6cd5\u5f8b\u5206\u6790\uff0c\u5e76\u63a2\u8ba8\u89e3\u51b3\u8be5\u7c7b\u7ea0\u7eb7\u7684\u5e38\u89c1\u9014\u5f84\u3002\u5728\u7968\u636e\u7ea0\u7eb7\u6848\u4ef6\u4e2d\uff0c\u5408\u540c\u6210\u7acb\u3001\u7968\u636e\u80cc\u4e66\u3001\u7968\u636e\u76d6\u7ae0\u7b49\u73af\u8282\u90fd\u9700\u8981\u7ecf\u8fc7\u8ba4\u771f\u5ba1\u89c6\u548c\u6cd5\u5f8b\u5206\u6790\u3002\u5f53\u4e8b\u4eba\u53ef\u4ee5\u901a\u8fc7\u534f\u5546\u3001\u8c03\u89e3\u6216\u8005\u8bc9\u8bbc\u7b49\u65b9\u5f0f\u89e3\u51b3\u4e89\u8bae\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9361687 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9361687\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df6d735\" data-id=\"df6d735\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45f0065 elementor-widget elementor-widget-heading\" data-id=\"45f0065\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u4e00\u3001\u5408\u540c\u6210\u7acb\u73af\u8282<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-959cd4b elementor-widget elementor-widget-text-editor\" data-id=\"959cd4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0\u7968\u636e\u7ea0\u7eb7\u7684\u9996\u8981\u95ee\u9898\u662f\u786e\u8ba4\u7968\u636e\u7684\u5408\u540c\u6210\u7acb\u3002\u5728\u7968\u636e\u4ea4\u6613\u4e2d\uff0c\u5f53\u4e8b\u4eba\u5e94\u5f53\u9075\u5faa\u76f8\u5173\u6cd5\u5f8b\u89c4\u5b9a\uff0c\u5305\u62ec\u300a\u7968\u636e\u6cd5\u300b\u7b49\uff0c\u786e\u4fdd\u5408\u540c\u6210\u7acb\u7684\u57fa\u672c\u8981\u7d20\uff0c\u5982\u5408\u540c\u4e3b\u4f53\u7684\u6c11\u4e8b\u884c\u4e3a\u80fd\u529b\u3001\u5408\u540c\u5185\u5bb9\u7684\u660e\u786e\u6027\u548c\u5408\u6cd5\u6027\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b45e231 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b45e231\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b3068bd\" data-id=\"b3068bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2e8ede elementor-widget elementor-widget-heading\" data-id=\"f2e8ede\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u4e8c\u3001\u7968\u636e\u7684\u80cc\u4e66<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1acbdcb elementor-widget elementor-widget-text-editor\" data-id=\"1acbdcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0\u7968\u636e\u80cc\u4e66\u662f\u7968\u636e\u6d41\u8f6c\u7684\u91cd\u8981\u73af\u8282\uff0c\u4e5f\u662f\u4ea7\u751f\u7ea0\u7eb7\u7684\u5173\u952e\u70b9\u4e4b\u4e00\u3002\u80cc\u4e66\u4eba\u6709\u6743\u5c06\u7968\u636e\u7684\u6743\u5229\u8f6c\u8ba9\u7ed9\u4ed6\u4eba\uff0c\u4f46\u5e94\u9075\u5b88\u7968\u636e\u6cd5\u7684\u89c4\u5b9a\u3002\u5982\u679c\u7968\u636e\u7684\u80cc\u4e66\u6743\u5229\u672a\u6309\u7167\u89c4\u5b9a\u8fdb\u884c\uff0c\u53ef\u80fd\u5bfc\u81f4\u7ea0\u7eb7\u7684\u53d1\u751f\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-685bd38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"685bd38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c3dfa23\" data-id=\"c3dfa23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4adb47c elementor-widget elementor-widget-heading\" data-id=\"4adb47c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u4e09\u3001\u7968\u636e\u76d6\u7ae0<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b67e1e7 elementor-widget elementor-widget-text-editor\" data-id=\"b67e1e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0\u7968\u636e\u7ea0\u7eb7\u4e2d\uff0c\u7968\u636e\u76d6\u7ae0\u7684\u95ee\u9898\u4e5f\u9700\u8981\u8fdb\u884c\u6cd5\u5f8b\u5206\u6790\u3002\u7968\u636e\u5e94\u5f53\u7ecf\u8fc7\u5408\u6cd5\u76d6\u7ae0\uff0c\u4ee5\u786e\u4fdd\u7968\u636e\u7684\u6709\u6548\u6027\u548c\u771f\u5b9e\u6027\u3002\u5982\u679c\u5b58\u5728\u76d6\u7ae0\u4e0d\u89c4\u8303\u3001\u76d6\u7ae0\u6743\u9650\u4e0d\u660e\u786e\u7b49\u60c5\u51b5\uff0c\u53ef\u80fd\u5bfc\u81f4\u7ea0\u7eb7\u7684\u4ea7\u751f\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-038e58d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"038e58d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99dd228\" data-id=\"99dd228\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17e9211 elementor-widget elementor-widget-heading\" data-id=\"17e9211\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u56db\u3001\u8bc1\u636e\u548c\u4e3e\u8bc1\u8d23\u4efb<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13d2c93 elementor-widget elementor-widget-text-editor\" data-id=\"13d2c93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0\u5728\u7968\u636e\u7ea0\u7eb7\u6848\u4ef6\u4e2d\uff0c\u5f53\u4e8b\u4eba\u9700\u8981\u63d0\u4f9b\u76f8\u5e94\u7684\u8bc1\u636e\u6765\u652f\u6301\u81ea\u5df1\u7684\u4e3b\u5f20\u3002\u5bf9\u4e8e\u7968\u636e\u7684\u80cc\u4e66\u3001\u76d6\u7ae0\u7b49\u95ee\u9898\uff0c\u5f53\u4e8b\u4eba\u5e94\u5f53\u63d0\u4f9b\u76f8\u5173\u7684\u7968\u636e\u539f\u4ef6\u3001\u5408\u540c\u3001\u4ea4\u6613\u8bb0\u5f55\u7b49\u8bc1\u636e\u3002\u5f53\u4e8b\u4eba\u6709\u4e3e\u8bc1\u8d23\u4efb\uff0c\u9700\u8981\u5145\u5206\u51c6\u5907\u548c\u7504\u522b\u8bc1\u636e\uff0c\u4ee5\u652f\u6301\u81ea\u5df1\u7684\u6743\u76ca\u4e3b\u5f20\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47a1a62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47a1a62\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f2c9c7\" data-id=\"3f2c9c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ee96ec elementor-widget elementor-widget-heading\" data-id=\"1ee96ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u4e94\u3001\u89e3\u51b3\u9014\u5f84<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2850b7c elementor-widget elementor-widget-text-editor\" data-id=\"2850b7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0\u534f\u5546\u548c\u8c03\u89e3\uff1a\u5f53\u4e8b\u4eba\u53ef\u4ee5\u901a\u8fc7\u534f\u5546\u548c\u8c03\u89e3\u5bfb\u6c42\u5171\u8bc6\uff0c\u4ee5\u8fbe\u6210\u4e00\u81f4\u610f\u89c1\u5e76\u89e3\u51b3\u7ea0\u7eb7\u3002\u8fd9\u79cd\u65b9\u5f0f\u53ef\u4ee5\u51cf\u5c11\u4e89\u8bae\u6210\u672c\uff0c\u4fdd\u62a4\u5f53\u4e8b\u4eba\u7684\u5408\u6cd5\u6743\u76ca\u3002<\/p><p>\u00a0\u4ef2\u88c1\uff1a\u5f53\u4e8b\u4eba\u53ef\u4ee5\u9009\u62e9\u5c06\u7ea0\u7eb7\u63d0\u4ea4\u4ef2\u88c1\u673a\u6784\u8fdb\u884c\u4ef2\u88c1\u3002\u4ef2\u88c1\u7a0b\u5e8f\u76f8\u5bf9\u7b80\u4fbf\uff0c\u5177\u6709\u72ec\u7acb\u6027\u548c\u516c\u6b63\u6027\uff0c\u5e76\u4e14\u4ef2\u88c1\u88c1\u51b3\u6709\u6cd5\u5f8b\u6548\u529b\u3002<\/p><p>\u00a0\u8bc9\u8bbc\uff1a\u4f5c\u4e3a\u6700\u540e\u7684\u89e3\u51b3\u9014\u5f84\uff0c\u5f53\u4e8b\u4eba\u53ef\u4ee5\u5c06\u7ea0\u7eb7\u63d0\u4ea4\u6cd5\u9662\u8fdb\u884c\u8bc9\u8bbc\u3002\u6cd5\u9662\u4f1a\u6839\u636e\u76f8\u5173\u6cd5\u5f8b\u89c4\u5b9a\u8fdb\u884c\u5ba1\u7406\uff0c\u5e76\u4f5c\u51fa\u88c1\u51b3\u6216\u5224\u51b3\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a219b4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a219b4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fb5daf4\" data-id=\"fb5daf4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b59891d elementor-widget elementor-widget-heading\" data-id=\"b59891d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u516d\u3001\u7ed3\u8bba<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a8d486 elementor-widget elementor-widget-text-editor\" data-id=\"7a8d486\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0\u5728\u5904\u7406\u7968\u636e\u7ea0\u7eb7\u65f6\uff0c\u5f53\u4e8b\u4eba\u5e94\u5f53\u5145\u5206\u7406\u89e3\u76f8\u5173\u6cd5\u5f8b\u89c4\u5b9a\uff0c\u5e76\u8fdb\u884c\u8ba4\u771f\u7684\u6cd5\u5f8b\u5206\u6790\u3002\u901a\u8fc7\u5408\u540c\u6210\u7acb\u7684\u5ba1\u89c6\u3001\u80cc\u4e66\u548c\u76d6\u7ae0\u7684\u5408\u6cd5\u6027\u68c0\u67e5\u3001\u5145\u5206\u51c6\u5907\u8bc1\u636e\u7b49\uff0c\u53ef\u4ee5\u5e2e\u52a9\u5f53\u4e8b\u4eba\u66f4\u597d\u5730\u7ef4\u62a4\u81ea\u5df1\u7684\u6743\u76ca\u3002\u540c\u65f6\uff0c\u5bfb\u6c42\u534f\u5546\u3001\u8c03\u89e3\u3001\u4ef2\u88c1\u6216\u8bc9\u8bbc\u7b49\u591a\u79cd\u89e3\u51b3\u9014\u5f84\uff0c\u9009\u62e9\u9002\u5f53\u7684\u65b9\u5f0f\u89e3\u51b3\u7ea0\u7eb7\uff0c\u4ee5\u5b9e\u73b0\u516c\u6b63\u548c\u5408\u6cd5\u7684\u7ed3\u679c\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5fbe7a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5fbe7a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a30121d\" data-id=\"a30121d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0578b84 elementor-widget elementor-widget-author-box\" data-id=\"0578b84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"author-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-author-box\">\r\n\t\t\t\t\t\t\t<a href=\"\/en\/xu-jie\/\" class=\"elementor-author-box__avatar\">\r\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.oc-lawyers.com.cn\/wp-content\/uploads\/2011\/03\/OC-Law-Firm-Lawyer-Mr-Xu-Jie.jpg\" alt=\"Picture of \u5f90\u6770\" loading=\"lazy\">\r\n\t\t\t\t<\/a>\r\n\t\t\t\r\n\t\t\t<div class=\"elementor-author-box__text\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"\/en\/xu-jie\/\">\r\n\t\t\t\t\t\t<h4 class=\"elementor-author-box__name\">\r\n\t\t\t\t\t\t\tXu Jie\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-author-box__bio\">\r\n\t\t\t\t\t\t<p>Associate<\/p>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u672c\u6587\u65e8\u5728\u5bf9\u7968\u636e\u7ea0\u7eb7\u6848\u4ef6\u8fdb\u884c\u6cd5\u5f8b\u5206\u6790\uff0c\u5e76\u63a2\u8ba8\u89e3\u51b3\u8be5\u7c7b\u7ea0\u7eb7\u7684\u5e38\u89c1\u9014\u5f84\u3002\u5728\u7968\u636e\u7ea0\u7eb7\u6848\u4ef6\u4e2d\uff0c\u5408\u540c\u6210\u7acb\u3001\u7968\u636e\u80cc\u4e66\u3001\u7968\u636e\u76d6\u7ae0\u7b49\u73af\u8282\u90fd\u9700\u8981\u7ecf\u8fc7\u8ba4\u771f\u5ba1\u89c6\u548c\u6cd5\u5f8b\u5206\u6790\u3002\u5f53\u4e8b\u4eba\u53ef\u4ee5\u901a\u8fc7\u534f\u5546\u3001\u8c03\u89e3\u6216\u8005\u8bc9\u8bbc\u7b49\u65b9\u5f0f\u89e3\u51b3\u4e89\u8bae\u3002<\/p>","protected":false},"author":2,"featured_media":8627,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[38,37],"tags":[171,73,39,56,79],"class_list":["post-8981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-articles","category-essays","tag-evidential-burden","tag-arbitration","tag-contract-law","tag-civil-procedure","tag-mediation"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.oc-lawyers.com.cn\/en\/wp-json\/wp\/v2\/posts\/8981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oc-lawyers.com.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oc-lawyers.com.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oc-lawyers.com.cn\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oc-lawyers.com.cn\/en\/wp-json\/wp\/v2\/comments?post=8981"}],"version-history":[{"count":0,"href":"https:\/\/www.oc-lawyers.com.cn\/en\/wp-json\/wp\/v2\/posts\/8981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oc-lawyers.com.cn\/en\/wp-json\/wp\/v2\/media\/8627"}],"wp:attachment":[{"href":"https:\/\/www.oc-lawyers.com.cn\/en\/wp-json\/wp\/v2\/media?parent=8981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oc-lawyers.com.cn\/en\/wp-json\/wp\/v2\/categories?post=8981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oc-lawyers.com.cn\/en\/wp-json\/wp\/v2\/tags?post=8981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}